{"id":2,"count":0,"description":"","link":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/","name":"Ekonomija","slug":"ekonomija","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhiva Ekonomija - Direktno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/direktno.info\/index.php\/category\/ekonomija\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhiva Ekonomija - Direktno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/direktno.info\/index.php\/category\/ekonomija\/\" \/>\n<meta property=\"og:site_name\" content=\"Direktno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/direktno.info\\\/index.php\\\/category\\\/ekonomija\\\/\",\"url\":\"https:\\\/\\\/direktno.info\\\/index.php\\\/category\\\/ekonomija\\\/\",\"name\":\"Arhiva Ekonomija - Direktno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/direktno.info\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/direktno.info\\\/index.php\\\/category\\\/ekonomija\\\/#breadcrumb\"},\"inLanguage\":\"hr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/direktno.info\\\/index.php\\\/category\\\/ekonomija\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\\\/\\\/direktno.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekonomija\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/direktno.info\\\/#website\",\"url\":\"https:\\\/\\\/direktno.info\\\/\",\"name\":\"Direktno\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/direktno.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/direktno.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/direktno.info\\\/#organization\",\"name\":\"Direktno\",\"url\":\"https:\\\/\\\/direktno.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/direktno.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/direktno.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/direktno_logo_white.png\",\"contentUrl\":\"https:\\\/\\\/direktno.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/direktno_logo_white.png\",\"width\":1600,\"height\":340,\"caption\":\"Direktno\"},\"image\":{\"@id\":\"https:\\\/\\\/direktno.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1Jy4gXyc5u\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhiva Ekonomija - Direktno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/","og_locale":"hr_HR","og_type":"article","og_title":"Arhiva Ekonomija - Direktno","og_url":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/","og_site_name":"Direktno","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/","url":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/","name":"Arhiva Ekonomija - Direktno","isPartOf":{"@id":"https:\/\/direktno.info\/#website"},"breadcrumb":{"@id":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/#breadcrumb"},"inLanguage":"hr"},{"@type":"BreadcrumbList","@id":"https:\/\/direktno.info\/index.php\/category\/ekonomija\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/direktno.info\/"},{"@type":"ListItem","position":2,"name":"Ekonomija"}]},{"@type":"WebSite","@id":"https:\/\/direktno.info\/#website","url":"https:\/\/direktno.info\/","name":"Direktno","description":"","publisher":{"@id":"https:\/\/direktno.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/direktno.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/direktno.info\/#organization","name":"Direktno","url":"https:\/\/direktno.info\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/direktno.info\/#\/schema\/logo\/image\/","url":"https:\/\/direktno.info\/wp-content\/uploads\/2026\/08\/direktno_logo_white.png","contentUrl":"https:\/\/direktno.info\/wp-content\/uploads\/2026\/08\/direktno_logo_white.png","width":1600,"height":340,"caption":"Direktno"},"image":{"@id":"https:\/\/direktno.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1Jy4gXyc5u\/"]}]}},"_links":{"self":[{"href":"https:\/\/direktno.info\/index.php\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/direktno.info\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/direktno.info\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/direktno.info\/index.php\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}